{"id":30532,"date":"2025-08-25T11:19:39","date_gmt":"2025-08-25T09:19:39","guid":{"rendered":"https:\/\/www.enocean.com\/?p=30532"},"modified":"2025-08-26T13:35:04","modified_gmt":"2025-08-26T11:35:04","slug":"mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender","status":"publish","type":"post","link":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/","title":{"rendered":"Mit EnOcean und Switchshop werden R\u00e4ume intelligenter, umweltschonender und ges\u00fcnder"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">In Bildung, \u00f6ffentlichen Diensten und in Unternehmen w\u00e4chst der Druck auf Immobilienverwalter: Sie sollen Energie sparen, den Komfort verbessern und R\u00e4ume effizienter nutzen \u2013 mit weniger Ressourcen und minimalen Betriebsunterbrechungen. Gemeinsam mit dem IT-Spezialisten <a href=\"https:\/\/www.switchshop.co.uk\/\">Switchshop <\/a>(Link nur im Vereinigten K\u00f6nigreich verf\u00fcgbar.) erm\u00f6glicht EnOcean genau das. Beide Unternehmen sind bew\u00e4hrte <a href=\"https:\/\/www.switchshop.co.uk\/partners\/hpe-aruba-networking\">Partner von HPE Aruba<\/a> (Link nur im Vereinigten K\u00f6nigreich verf\u00fcgbar.) und stellen ganzheitliche Smart-Building-L\u00f6sungen bereit, indem sie praxiserprobte Technologie und fundiertes Fachwissen vereinen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ganzheitliche L\u00f6sung aus einer Hand<\/strong><br>Mit Switchshop erreichen Kunden ihre Ziele mit einem erfahrenen Partner, der ihnen eine ganzheitliche \u201aEnd-to-End\u2018-L\u00f6sung anbietet. Mit zahlreichen Vorteilen: nur ein Lieferant, keine langwierigen Installationsprozesse und keine Unsicherheiten. Stattdessen sorgt ein engagiertes Projektmanagement f\u00fcr eine reibungslose und stressfreie Lieferung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Eine leistungsstarke Kombination<\/strong><br>Die L\u00f6sungen Estate IQ und OccuFi von Switchshop zeigen Immobilienverwaltern \u00fcberzeugend, wie ihre Geb\u00e4ude genutzt werden und wie gesund in diesen das Raumklima ist. Batterielose Sensoren von EnOcean, die Energie mittels \u201aEnergy Harvesting\u2018 autark gewinnen, liefern pr\u00e4zise Echtzeitdaten \u2013 ohne Kabel, Batteriewechsel oder aufwendige Installationen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da die L\u00f6sungen bestehende HPE Aruba-Netzwerke nutzen, k\u00f6nnen Unternehmen schnell und kosteng\u00fcnstig modernisieren, ohne den t\u00e4glichen Betrieb zu unterbrechen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zahlreiche Vorteile f\u00fcr Kunden<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Geringere Betriebskosten: <\/strong>Sie senken den Energieverbrauch f\u00fcr Heizung, K\u00fchlung und Beleuchtung um bis zu 25 %<\/li>\n\n\n\n<li><strong>Intelligentere Raumnutzung: <\/strong>Sie optimieren die Nutzung von R\u00e4umen, Schreibtischen und Geb\u00e4uden mit einer Effizienzsteigerung von bis zu 30 %<\/li>\n\n\n\n<li><strong>Verbessertes Raumklima:<\/strong> Sie messen Luftqualit\u00e4t, L\u00e4rm, Licht und Luftfeuchtigkeit und verbessern Komfort und Wohlbefinden der Nutzer<\/li>\n\n\n\n<li><strong>Schnellere Nachhaltigkeitsberichterstattung: <\/strong>Sie erreichen ESG-Ziele durch genaue und aktuelle Umweltdaten<\/li>\n\n\n\n<li><strong>Kein Wartungsaufwand: <\/strong>Batterielose Sensoren ersparen Ihnen einen stetigen Austausch und vermeiden Abfall<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Auswirkungen auf verschiedene Sektoren<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Bildungswesen: <\/strong>Sie passen Ressourcen in Schulen und Universit\u00e4ten an Nutzungsmuster an, verbessern die Sicherheit und steigern das Wohlbefinden der Sch\u00fcler und Studenten, auch in historischen Geb\u00e4uden oder rund um die Uhr ge\u00f6ffneten Internaten<\/li>\n\n\n\n<li><strong>\u00d6ffentlicher Sektor: <\/strong>Sie modernisieren ohne Unterbrechungen, erreichen Nachhaltigkeitsziele und erf\u00fcllen die Anforderungen der DSGVO und der Cybersicherheit<\/li>\n\n\n\n<li><strong>Unternehmenssektor: <\/strong>Sie gestalten B\u00fcror\u00e4ume f\u00fcr hybrides Arbeiten um und erschlie\u00dfen ungenutzte Fl\u00e4chen<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Diese Partnerschaft liefert Mehrwert<\/strong><br>Switchshop bringt sein Know-how aus IT und Analytik ein, EnOcean seine bew\u00e4hrte Sensortechnologie. Daraus resultieren L\u00f6sungen, die kosteng\u00fcnstiger, skalierbarer und sofort nutzbar sind. Als Teil des HPE Aruba-\u00d6kosystems unterst\u00fctzen wir Kunden, das volle Potenzial ihrer Geb\u00e4ude auszusch\u00f6pfen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ausblick<\/strong><br>Die Partnerschaft mit Switchshop steht erst der Anfang. Unsere Zusammenarbeit wird weiter wachsen und noch mehr Unternehmen helfen, Kosten zu senken, CO<sub>2<\/sub>-Emissionen zu reduzieren und das Nutzererlebnis in ihren R\u00e4umlichkeiten zu verbessern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Bildung, \u00f6ffentlichen Diensten und in Unternehmen w\u00e4chst der Druck auf Immobilienverwalter: Sie sollen Energie sparen, den Komfort verbessern und R\u00e4ume effizienter nutzen \u2013 mit weniger Ressourcen und minimalen Betriebsunterbrechungen. Gemeinsam mit dem IT-Spezialisten Switchshop (Link nur im Vereinigten K\u00f6nigreich verf\u00fcgbar.) erm\u00f6glicht EnOcean genau das. Beide Unternehmen sind bew\u00e4hrte Partner von HPE Aruba (Link nur [&hellip;]<\/p>\n","protected":false},"author":8938,"featured_media":30539,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"categories":[1789],"tags":[],"class_list":["post-30532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enocean-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mit EnOcean und Switchshop werden R\u00e4ume intelligenter, umweltschonender und ges\u00fcnder - EnOcean<\/title>\n<meta name=\"description\" content=\"EnOcean und Switchshop bieten smarte Geb\u00e4udel\u00f6sungen, die Kosten senken, Energie sparen und Komfort steigern\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mit EnOcean und Switchshop werden R\u00e4ume intelligenter, umweltschonender und ges\u00fcnder - EnOcean\" \/>\n<meta property=\"og:description\" content=\"EnOcean und Switchshop bieten smarte Geb\u00e4udel\u00f6sungen, die Kosten senken, Energie sparen und Komfort steigern\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/\" \/>\n<meta property=\"og:site_name\" content=\"EnOcean\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-25T09:19:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-26T11:35:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1700\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Matteo Bono\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matteo Bono\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/enocean-de\\\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/enocean-de\\\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\\\/\"},\"author\":{\"name\":\"Matteo Bono\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/#\\\/schema\\\/person\\\/110819fc2681a9eeb8bd36bfc250d723\"},\"headline\":\"Mit EnOcean und Switchshop werden R\u00e4ume intelligenter, umweltschonender und ges\u00fcnder\",\"datePublished\":\"2025-08-25T09:19:39+00:00\",\"dateModified\":\"2025-08-26T11:35:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/enocean-de\\\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\\\/\"},\"wordCount\":452,\"publisher\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/enocean-de\\\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.enocean.com\\\/wp-content\\\/uploads\\\/Blog\\\/Picture.png\",\"articleSection\":[\"EnOcean\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/enocean-de\\\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\\\/\",\"url\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/enocean-de\\\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\\\/\",\"name\":\"Mit EnOcean und Switchshop werden R\u00e4ume intelligenter, umweltschonender und ges\u00fcnder - EnOcean\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/enocean-de\\\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/enocean-de\\\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.enocean.com\\\/wp-content\\\/uploads\\\/Blog\\\/Picture.png\",\"datePublished\":\"2025-08-25T09:19:39+00:00\",\"dateModified\":\"2025-08-26T11:35:04+00:00\",\"description\":\"EnOcean und Switchshop bieten smarte Geb\u00e4udel\u00f6sungen, die Kosten senken, Energie sparen und Komfort steigern\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/enocean-de\\\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.enocean.com\\\/de\\\/enocean-de\\\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/enocean-de\\\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.enocean.com\\\/wp-content\\\/uploads\\\/Blog\\\/Picture.png\",\"contentUrl\":\"https:\\\/\\\/www.enocean.com\\\/wp-content\\\/uploads\\\/Blog\\\/Picture.png\",\"width\":1700,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/enocean-de\\\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mit EnOcean und Switchshop werden R\u00e4ume intelligenter, umweltschonender und ges\u00fcnder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/\",\"name\":\"EnOcean\",\"description\":\"EnOcean Relaunch\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/#organization\",\"name\":\"EnOcean\",\"url\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.enocean.com\\\/wp-content\\\/uploads\\\/Logos\\\/1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.enocean.com\\\/wp-content\\\/uploads\\\/Logos\\\/1-1.png\",\"width\":500,\"height\":500,\"caption\":\"EnOcean\"},\"image\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/enocean\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/#\\\/schema\\\/person\\\/110819fc2681a9eeb8bd36bfc250d723\",\"name\":\"Matteo Bono\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b518318d9bca3ae214bbb1a530c6d45b1ccdca92a0241622818bb2db450d5f7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b518318d9bca3ae214bbb1a530c6d45b1ccdca92a0241622818bb2db450d5f7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b518318d9bca3ae214bbb1a530c6d45b1ccdca92a0241622818bb2db450d5f7e?s=96&d=mm&r=g\",\"caption\":\"Matteo Bono\"},\"url\":\"https:\\\/\\\/www.enocean.com\\\/de\\\/author\\\/enocean_bono\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mit EnOcean und Switchshop werden R\u00e4ume intelligenter, umweltschonender und ges\u00fcnder - EnOcean","description":"EnOcean und Switchshop bieten smarte Geb\u00e4udel\u00f6sungen, die Kosten senken, Energie sparen und Komfort steigern","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/","og_locale":"de_DE","og_type":"article","og_title":"Mit EnOcean und Switchshop werden R\u00e4ume intelligenter, umweltschonender und ges\u00fcnder - EnOcean","og_description":"EnOcean und Switchshop bieten smarte Geb\u00e4udel\u00f6sungen, die Kosten senken, Energie sparen und Komfort steigern","og_url":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/","og_site_name":"EnOcean","article_published_time":"2025-08-25T09:19:39+00:00","article_modified_time":"2025-08-26T11:35:04+00:00","og_image":[{"width":1700,"height":800,"url":"https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture.png","type":"image\/png"}],"author":"Matteo Bono","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Matteo Bono","Gesch\u00e4tzte Lesezeit":"2\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/#article","isPartOf":{"@id":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/"},"author":{"name":"Matteo Bono","@id":"https:\/\/www.enocean.com\/de\/#\/schema\/person\/110819fc2681a9eeb8bd36bfc250d723"},"headline":"Mit EnOcean und Switchshop werden R\u00e4ume intelligenter, umweltschonender und ges\u00fcnder","datePublished":"2025-08-25T09:19:39+00:00","dateModified":"2025-08-26T11:35:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/"},"wordCount":452,"publisher":{"@id":"https:\/\/www.enocean.com\/de\/#organization"},"image":{"@id":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/#primaryimage"},"thumbnailUrl":"https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture.png","articleSection":["EnOcean"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/","url":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/","name":"Mit EnOcean und Switchshop werden R\u00e4ume intelligenter, umweltschonender und ges\u00fcnder - EnOcean","isPartOf":{"@id":"https:\/\/www.enocean.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/#primaryimage"},"image":{"@id":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/#primaryimage"},"thumbnailUrl":"https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture.png","datePublished":"2025-08-25T09:19:39+00:00","dateModified":"2025-08-26T11:35:04+00:00","description":"EnOcean und Switchshop bieten smarte Geb\u00e4udel\u00f6sungen, die Kosten senken, Energie sparen und Komfort steigern","breadcrumb":{"@id":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/#primaryimage","url":"https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture.png","contentUrl":"https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture.png","width":1700,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.enocean.com\/de\/enocean-de\/mit-enocean-und-switchshop-werden-raeume-intelligenter-umweltschonender-und-gesuender\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.enocean.com\/de\/"},{"@type":"ListItem","position":2,"name":"Mit EnOcean und Switchshop werden R\u00e4ume intelligenter, umweltschonender und ges\u00fcnder"}]},{"@type":"WebSite","@id":"https:\/\/www.enocean.com\/de\/#website","url":"https:\/\/www.enocean.com\/de\/","name":"EnOcean","description":"EnOcean Relaunch","publisher":{"@id":"https:\/\/www.enocean.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.enocean.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.enocean.com\/de\/#organization","name":"EnOcean","url":"https:\/\/www.enocean.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.enocean.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.enocean.com\/wp-content\/uploads\/Logos\/1-1.png","contentUrl":"https:\/\/www.enocean.com\/wp-content\/uploads\/Logos\/1-1.png","width":500,"height":500,"caption":"EnOcean"},"image":{"@id":"https:\/\/www.enocean.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/enocean\/"]},{"@type":"Person","@id":"https:\/\/www.enocean.com\/de\/#\/schema\/person\/110819fc2681a9eeb8bd36bfc250d723","name":"Matteo Bono","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/b518318d9bca3ae214bbb1a530c6d45b1ccdca92a0241622818bb2db450d5f7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b518318d9bca3ae214bbb1a530c6d45b1ccdca92a0241622818bb2db450d5f7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b518318d9bca3ae214bbb1a530c6d45b1ccdca92a0241622818bb2db450d5f7e?s=96&d=mm&r=g","caption":"Matteo Bono"},"url":"https:\/\/www.enocean.com\/de\/author\/enocean_bono\/"}]}},"taxonomy_info":{"category":[{"value":1789,"label":"EnOcean"}]},"featured_image_src_large":["https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture-1024x482.png",1024,482,true],"author_info":{"display_name":"Matteo Bono","author_link":"https:\/\/www.enocean.com\/de\/author\/enocean_bono\/"},"comment_info":0,"category_info":[{"term_id":1789,"name":"EnOcean","slug":"enocean-de","term_group":0,"term_taxonomy_id":1789,"taxonomy":"category","description":"","parent":0,"count":15,"filter":"raw","term_order":"0","cat_ID":1789,"category_count":15,"category_description":"","cat_name":"EnOcean","category_nicename":"enocean-de","category_parent":0}],"tag_info":false,"uagb_featured_image_src":{"full":["https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture.png",1700,800,false],"thumbnail":["https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture-150x71.png",150,71,true],"medium":["https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture-300x141.png",300,141,true],"medium_large":["https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture-768x361.png",768,361,true],"large":["https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture-1024x482.png",1024,482,true],"1536x1536":["https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture-1536x723.png",1536,723,true],"2048x2048":["https:\/\/www.enocean.com\/wp-content\/uploads\/Blog\/Picture.png",1700,800,false]},"uagb_author_info":{"display_name":"Matteo Bono","author_link":"https:\/\/www.enocean.com\/de\/author\/enocean_bono\/"},"uagb_comment_info":0,"uagb_excerpt":"In Bildung, \u00f6ffentlichen Diensten und in Unternehmen w\u00e4chst der Druck auf Immobilienverwalter: Sie sollen Energie sparen, den Komfort verbessern und R\u00e4ume effizienter nutzen \u2013 mit weniger Ressourcen und minimalen Betriebsunterbrechungen. Gemeinsam mit dem IT-Spezialisten Switchshop (Link nur im Vereinigten K\u00f6nigreich verf\u00fcgbar.) erm\u00f6glicht EnOcean genau das. Beide Unternehmen sind bew\u00e4hrte Partner von HPE Aruba (Link nur&hellip;","_links":{"self":[{"href":"https:\/\/www.enocean.com\/de\/wp-json\/wp\/v2\/posts\/30532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enocean.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enocean.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enocean.com\/de\/wp-json\/wp\/v2\/users\/8938"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enocean.com\/de\/wp-json\/wp\/v2\/comments?post=30532"}],"version-history":[{"count":3,"href":"https:\/\/www.enocean.com\/de\/wp-json\/wp\/v2\/posts\/30532\/revisions"}],"predecessor-version":[{"id":30548,"href":"https:\/\/www.enocean.com\/de\/wp-json\/wp\/v2\/posts\/30532\/revisions\/30548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enocean.com\/de\/wp-json\/wp\/v2\/media\/30539"}],"wp:attachment":[{"href":"https:\/\/www.enocean.com\/de\/wp-json\/wp\/v2\/media?parent=30532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enocean.com\/de\/wp-json\/wp\/v2\/categories?post=30532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enocean.com\/de\/wp-json\/wp\/v2\/tags?post=30532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}