{"id":9855,"date":"2021-09-23T12:30:03","date_gmt":"2021-09-23T12:30:03","guid":{"rendered":"https:\/\/www.enocean.com\/?page_id=9855"},"modified":"2025-03-11T10:09:06","modified_gmt":"2025-03-11T09:09:06","slug":"enocean-products-select-radio-frequency","status":"publish","type":"page","link":"https:\/\/www.enocean.com\/en\/applications\/partnerships\/enocean-products-select-radio-frequency\/","title":{"rendered":"EnOcean Radio Frequency Selection"},"content":{"rendered":"\n<div class=\"wp-block-cover is-light eo-visualheader\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#ccd5de\"><\/span><img decoding=\"async\" width=\"2048\" height=\"613\" class=\"wp-block-cover__image-background wp-image-27146\" alt=\"EnOcean Radio Technology\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_RadioTechnologie_2048x613.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_RadioTechnologie_2048x613.jpg 2048w, https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_RadioTechnologie_2048x613-300x90.jpg 300w, https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_RadioTechnologie_2048x613-1024x307.jpg 1024w, https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_RadioTechnologie_2048x613-150x45.jpg 150w, https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_RadioTechnologie_2048x613-768x230.jpg 768w, https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_RadioTechnologie_2048x613-1536x460.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-f06fba9a\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<h1 class=\"wp-block-heading\">IoT sensors at a glance \u2013 the EnOcean portfolio<\/h1>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_a04ed3-26 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_a04ed3-26 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_a04ed3-26\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">EnOcean wireless sensors are based on the patented energy harvesting technology. They collect their energy from small solar cells, button pressure or temperature differences. For your IoT project this means that you can reposition the sensors flexibly again and again, because no wiring or battery replacement is necessary. Products include occupancy, acceleration and motion-sensors, window and magnetic-contacts, temperature and humidity-sensors and a multisensor.<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_1af420-04 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_1af420-04 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_1af420-04\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"463\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Schmuckbilder\/enocean-partnerships-product-portfolio-1024x463-1.jpg\" alt=\"EnOcean Product Portfolio\" class=\"wp-image-13156\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Schmuckbilder\/enocean-partnerships-product-portfolio-1024x463-1.jpg 1024w, https:\/\/www.enocean.com\/wp-content\/uploads\/Schmuckbilder\/enocean-partnerships-product-portfolio-1024x463-1-300x136.jpg 300w, https:\/\/www.enocean.com\/wp-content\/uploads\/Schmuckbilder\/enocean-partnerships-product-portfolio-1024x463-1-150x68.jpg 150w, https:\/\/www.enocean.com\/wp-content\/uploads\/Schmuckbilder\/enocean-partnerships-product-portfolio-1024x463-1-768x347.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_6e486d-92 .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-9855_6e486d-92 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_6e486d-92\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-9c297df8\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<h2 class=\"wp-block-heading\"> Please select the radio frequency for your region: <\/h2>\n\n\n<style>.kt-accordion-id9855_d2d313-e0 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:1px;}.kt-accordion-id9855_d2d313-e0 .kt-accordion-panel-inner{border-top:0px solid #FFFFFF;border-right:0px solid #FFFFFF;border-bottom:0px solid #FFFFFF;border-left:0px solid #FFFFFF;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#ffffff;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id9855_d2d313-e0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#cccccc;border-top-style:solid;border-right-color:#cccccc;border-right-style:solid;border-bottom-color:#cccccc;border-bottom-style:solid;border-left-color:#cccccc;border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#ffffff;font-size:18px;line-height:24px;color:#003274;padding-top:18px;padding-right:16px;padding-bottom:18px;padding-left:16px;}.kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#003274;}.kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#003274;}.kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id9855_d2d313-e0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id9855_d2d313-e0 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#ffffff;border-top-color:#FFFFFF;border-top-style:solid;border-right-color:#FFFFFF;border-right-style:solid;border-bottom-color:#FFFFFF;border-bottom-style:solid;border-left-color:#FFFFFF;border-left-style:solid;}.kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id9855_d2d313-e0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id9855_d2d313-e0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#003274;background:#ffffff;border-top-color:#FFFFFF;border-top-style:solid;border-right-color:#FFFFFF;border-right-style:solid;border-bottom-color:#FFFFFF;border-bottom-style:solid;border-left-color:#FFFFFF;border-left-style:solid;}.kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#003274;}.kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#003274;}.kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id9855_d2d313-e0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}@media all and (max-width: 1024px){.kt-accordion-id9855_d2d313-e0 .kt-accordion-panel-inner{border-top:0px solid #FFFFFF;border-right:0px solid #FFFFFF;border-bottom:0px solid #FFFFFF;border-left:0px solid #FFFFFF;}}@media all and (max-width: 1024px){.kt-accordion-id9855_d2d313-e0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#cccccc;border-top-style:solid;border-right-color:#cccccc;border-right-style:solid;border-bottom-color:#cccccc;border-bottom-style:solid;border-left-color:#cccccc;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id9855_d2d313-e0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id9855_d2d313-e0 .kt-blocks-accordion-header:focus-visible{border-top-color:#FFFFFF;border-top-style:solid;border-right-color:#FFFFFF;border-right-style:solid;border-bottom-color:#FFFFFF;border-bottom-style:solid;border-left-color:#FFFFFF;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id9855_d2d313-e0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id9855_d2d313-e0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#FFFFFF;border-top-style:solid;border-right-color:#FFFFFF;border-right-style:solid;border-bottom-color:#FFFFFF;border-bottom-style:solid;border-left-color:#FFFFFF;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id9855_d2d313-e0 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id9855_d2d313-e0 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:1px;}.kt-accordion-id9855_d2d313-e0 .kt-accordion-panel-inner{border-top:0px solid #FFFFFF;border-right:0px solid #FFFFFF;border-bottom:0px solid #FFFFFF;border-left:0px solid #FFFFFF;}.kt-accordion-id9855_d2d313-e0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#cccccc;border-top-style:solid;border-right-color:#cccccc;border-right-style:solid;border-bottom-color:#cccccc;border-bottom-style:solid;border-left-color:#cccccc;border-left-style:solid;}.kt-accordion-id9855_d2d313-e0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id9855_d2d313-e0 .kt-blocks-accordion-header:focus-visible{border-top-color:#FFFFFF;border-top-style:solid;border-right-color:#FFFFFF;border-right-style:solid;border-bottom-color:#FFFFFF;border-bottom-style:solid;border-left-color:#FFFFFF;border-left-style:solid;}.kt-accordion-id9855_d2d313-e0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id9855_d2d313-e0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#FFFFFF;border-top-style:solid;border-right-color:#FFFFFF;border-right-style:solid;border-bottom-color:#FFFFFF;border-bottom-style:solid;border-left-color:#FFFFFF;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id9855_d2d313-e0 kt-accordion-has-20-panes kt-active-pane-14 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-xclosecircle kt-accodion-icon-side-left\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-20 kt-pane9855_67752b-95\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Europe &#8211; 868 Mhz (supported by Aruba systems) <\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">IoT Multisensor &#8211; EMSIA (OEM)<\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Magnet Contact Sensor &#8211; EMCSA (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"307\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMCS_2_rgb_72dpi_f49d2e11b4_0015a25d4e_b74451e53d.jpg\" alt=\"\" class=\"wp-image-10128\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMCS_2_rgb_72dpi_f49d2e11b4_0015a25d4e_b74451e53d.jpg 307w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMCS_2_rgb_72dpi_f49d2e11b4_0015a25d4e_b74451e53d-300x225.jpg 300w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMCS_2_rgb_72dpi_f49d2e11b4_0015a25d4e_b74451e53d-150x112.jpg 150w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_6fead5-2e .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_6fead5-2e .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_6fead5-2e\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Temperature &amp; Humidity Sensor &#8211; ETHSA (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"307\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_ETHS_1_rgb_72dpi_02_f3400bf4d9_5ebc7c79c4_101d0c9ed0.jpg\" alt=\"\" class=\"wp-image-10155\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_ETHS_1_rgb_72dpi_02_f3400bf4d9_5ebc7c79c4_101d0c9ed0.jpg 307w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_ETHS_1_rgb_72dpi_02_f3400bf4d9_5ebc7c79c4_101d0c9ed0-300x225.jpg 300w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_ETHS_1_rgb_72dpi_02_f3400bf4d9_5ebc7c79c4_101d0c9ed0-150x112.jpg 150w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Motion Detector with Illumination Sensor &#8211; EMDCA (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"230\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMDCB-1000px_02_41219579cf_3a10c2fd2d_e68dfa07a0.jpg\" alt=\"\" class=\"wp-image-10168\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMDCB-1000px_02_41219579cf_3a10c2fd2d_e68dfa07a0.jpg 230w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMDCB-1000px_02_41219579cf_3a10c2fd2d_e68dfa07a0-150x150.jpg 150w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_b81116-7c .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_b81116-7c .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_b81116-7c\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Ceiling Mounted Occupancy Sensor &#8211; EOSCA (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"111\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_12_1be89bf15b_90818bfd60_7dbd242e31.jpg\" alt=\"\" class=\"wp-image-10149\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_12_1be89bf15b_90818bfd60_7dbd242e31.jpg 111w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_12_1be89bf15b_90818bfd60_7dbd242e31-72x150.jpg 72w\" sizes=\"(max-width: 111px) 100vw, 111px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Wall Mounted Occupancy Sensor &#8211; EOSWA (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"97\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_sensor_occupancy-wall_EOSW_02_6a4b192734_faf3b8c6f6_a724ae03f6.jpg\" alt=\"\" class=\"wp-image-10161\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_sensor_occupancy-wall_EOSW_02_6a4b192734_faf3b8c6f6_a724ae03f6.jpg 97w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_sensor_occupancy-wall_EOSW_02_6a4b192734_faf3b8c6f6_a724ae03f6-63x150.jpg 63w\" sizes=\"(max-width: 97px) 100vw, 97px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_3feb03-cc .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_3feb03-cc .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_3feb03-cc\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">EnOcean People Activity Counter &#8211; EPACA<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"111\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_2b2b5034e8_976e6f8a8c_4bef43308d.jpg\" alt=\"\" class=\"wp-image-10146\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_2b2b5034e8_976e6f8a8c_4bef43308d.jpg 111w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_2b2b5034e8_976e6f8a8c_4bef43308d-72x150.jpg 72w\" sizes=\"(max-width: 111px) 100vw, 111px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Occupancy Sensor Sub Desk &#8211; EOSDA<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"114\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSD_9303e64547_0525a87c97_7c13e4ec1d.jpg\" alt=\"\" class=\"wp-image-10152\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSD_9303e64547_0525a87c97_7c13e4ec1d.jpg 114w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSD_9303e64547_0525a87c97_7c13e4ec1d-74x150.jpg 74w\" sizes=\"(max-width: 114px) 100vw, 114px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_340e15-50 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_340e15-50 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_340e15-50\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">USB 300 (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"230\" height=\"173\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/enocean-usb-stick.jpg\" alt=\"\" class=\"wp-image-10164\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/enocean-usb-stick.jpg 230w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/enocean-usb-stick-150x113.jpg 150w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\"><\/h4>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-16 kt-pane9855_1d82c1-f3\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">North America &#8211; 902 Mhz<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Wireless Switch &#8211; ESRPU \/ EDRPU (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"230\" height=\"202\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_switch_rocker-pads_single-double_72_7eb8821c27_7b4f23fd32_6a3fd4ffe6.jpg\" alt=\"\" class=\"wp-image-10191\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_switch_rocker-pads_single-double_72_7eb8821c27_7b4f23fd32_6a3fd4ffe6.jpg 230w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_switch_rocker-pads_single-double_72_7eb8821c27_7b4f23fd32_6a3fd4ffe6-150x132.jpg 150w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">IoT Multisensor &#8211; EMSIU (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"230\" height=\"205\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_Oct2019_02_11f56ee000_1bd2d17012_2eda57640f.jpg\" alt=\"\" class=\"wp-image-10131\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_Oct2019_02_11f56ee000_1bd2d17012_2eda57640f.jpg 230w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_Oct2019_02_11f56ee000_1bd2d17012_2eda57640f-150x134.jpg 150w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_4d681c-a8 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_4d681c-a8 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_4d681c-a8\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Magnet Contact Sensor &#8211; EMCSU (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"307\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMCS_2_rgb_72dpi_f49d2e11b4_0015a25d4e_b74451e53d.jpg\" alt=\"\" class=\"wp-image-10128\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMCS_2_rgb_72dpi_f49d2e11b4_0015a25d4e_b74451e53d.jpg 307w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMCS_2_rgb_72dpi_f49d2e11b4_0015a25d4e_b74451e53d-300x225.jpg 300w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMCS_2_rgb_72dpi_f49d2e11b4_0015a25d4e_b74451e53d-150x112.jpg 150w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Temperature &amp; Humidity Sensor &#8211; ETHSU (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"307\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_ETHS_1_rgb_72dpi_75e0296622_53d2785cd6_2e776950f9.jpg\" alt=\"\" class=\"wp-image-10196\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_ETHS_1_rgb_72dpi_75e0296622_53d2785cd6_2e776950f9.jpg 307w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_ETHS_1_rgb_72dpi_75e0296622_53d2785cd6_2e776950f9-300x225.jpg 300w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_ETHS_1_rgb_72dpi_75e0296622_53d2785cd6_2e776950f9-150x112.jpg 150w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_a0ab33-3d .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_a0ab33-3d .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_a0ab33-3d\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Motion Detector with Illumination Sensor &#8211; EMDCU (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"230\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMDCB-1000px_02_41219579cf_3a10c2fd2d_e68dfa07a0.jpg\" alt=\"\" class=\"wp-image-10168\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMDCB-1000px_02_41219579cf_3a10c2fd2d_e68dfa07a0.jpg 230w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMDCB-1000px_02_41219579cf_3a10c2fd2d_e68dfa07a0-150x150.jpg 150w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Ceiling Mounted Occupancy Sensor &#8211; EOSCU (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"111\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_12_1be89bf15b_90818bfd60_7dbd242e31.jpg\" alt=\"\" class=\"wp-image-10149\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_12_1be89bf15b_90818bfd60_7dbd242e31.jpg 111w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_12_1be89bf15b_90818bfd60_7dbd242e31-72x150.jpg 72w\" sizes=\"(max-width: 111px) 100vw, 111px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_6fc27b-95 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_6fc27b-95 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_6fc27b-95\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Wall Mounted Occupancy Sensor &#8211; EOSWU (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"97\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_sensor_occupancy-wall_EOSW_02_6a4b192734_faf3b8c6f6_a724ae03f6.jpg\" alt=\"\" class=\"wp-image-10161\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_sensor_occupancy-wall_EOSW_02_6a4b192734_faf3b8c6f6_a724ae03f6.jpg 97w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_sensor_occupancy-wall_EOSW_02_6a4b192734_faf3b8c6f6_a724ae03f6-63x150.jpg 63w\" sizes=\"(max-width: 97px) 100vw, 97px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">EnOcean People Activity Counter &#8211; EPAC<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"111\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_12_1be89bf15b_90818bfd60_7dbd242e31.jpg\" alt=\"\" class=\"wp-image-10149\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_12_1be89bf15b_90818bfd60_7dbd242e31.jpg 111w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_12_1be89bf15b_90818bfd60_7dbd242e31-72x150.jpg 72w\" sizes=\"(max-width: 111px) 100vw, 111px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_ba8d29-6f .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_ba8d29-6f .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_ba8d29-6f\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Occupancy Sensor Sub Desk &#8211; EOSD<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"114\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSD_9303e64547_0525a87c97_7c13e4ec1d.jpg\" alt=\"\" class=\"wp-image-10152\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSD_9303e64547_0525a87c97_7c13e4ec1d.jpg 114w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSD_9303e64547_0525a87c97_7c13e4ec1d-74x150.jpg 74w\" sizes=\"(max-width: 114px) 100vw, 114px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Light Level Sensor &#8211; ELLSU (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"230\" height=\"173\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_ELLS_01_0fea0ab542_39c2ae2f96_72d7f32026.jpg\" alt=\"\" class=\"wp-image-10188\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_ELLS_01_0fea0ab542_39c2ae2f96_72d7f32026.jpg 230w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_ELLS_01_0fea0ab542_39c2ae2f96_72d7f32026-150x113.jpg 150w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_453d5b-e7 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_453d5b-e7 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_453d5b-e7\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">USB 500U<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"230\" height=\"173\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/enocean-usb-stick.jpg\" alt=\"\" class=\"wp-image-10164\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/enocean-usb-stick.jpg 230w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/enocean-usb-stick-150x113.jpg 150w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\"><\/h4>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-19 kt-pane9855_b5e8e3-ad\" id=\"trial-version\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Japan &#8211; 928 Mhz<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">IoT Multisensor &#8211; EMSIJ (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"230\" height=\"205\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_Oct2019_02_11f56ee000_1bd2d17012_2eda57640f.jpg\" alt=\"\" class=\"wp-image-10131\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_Oct2019_02_11f56ee000_1bd2d17012_2eda57640f.jpg 230w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_Oct2019_02_11f56ee000_1bd2d17012_2eda57640f-150x134.jpg 150w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Magnet Contact Sensor &#8211; EMCSJ (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"307\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMCS_2_rgb_72dpi_f49d2e11b4_0015a25d4e_b74451e53d.jpg\" alt=\"\" class=\"wp-image-10128\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMCS_2_rgb_72dpi_f49d2e11b4_0015a25d4e_b74451e53d.jpg 307w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMCS_2_rgb_72dpi_f49d2e11b4_0015a25d4e_b74451e53d-300x225.jpg 300w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMCS_2_rgb_72dpi_f49d2e11b4_0015a25d4e_b74451e53d-150x112.jpg 150w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_f9447e-b8 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_f9447e-b8 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_f9447e-b8\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Motion Detector with Illumination Sensor &#8211; EMDCJ (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"230\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMDCB-1000px_02_41219579cf_3a10c2fd2d_e68dfa07a0.jpg\" alt=\"\" class=\"wp-image-10168\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMDCB-1000px_02_41219579cf_3a10c2fd2d_e68dfa07a0.jpg 230w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EMDCB-1000px_02_41219579cf_3a10c2fd2d_e68dfa07a0-150x150.jpg 150w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Ceiling Mounted Occupancy Sensor &#8211; EOSCJ (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"111\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_12_1be89bf15b_90818bfd60_7dbd242e31.jpg\" alt=\"\" class=\"wp-image-10149\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_12_1be89bf15b_90818bfd60_7dbd242e31.jpg 111w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_EOSC_clear_lenses-lg_12_1be89bf15b_90818bfd60_7dbd242e31-72x150.jpg 72w\" sizes=\"(max-width: 111px) 100vw, 111px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_bb7325-1e .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_bb7325-1e .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_bb7325-1e\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns eo-single-row is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Wall Mounted Occupancy Sensor &#8211; EOSWJ (OEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"97\" height=\"230\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_sensor_occupancy-wall_EOSW_02_6a4b192734_faf3b8c6f6_a724ae03f6.jpg\" alt=\"\" class=\"wp-image-10161\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_sensor_occupancy-wall_EOSW_02_6a4b192734_faf3b8c6f6_a724ae03f6.jpg 97w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/csm_csm_sensor_occupancy-wall_EOSW_02_6a4b192734_faf3b8c6f6_a724ae03f6-63x150.jpg 63w\" sizes=\"(max-width: 97px) 100vw, 97px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column ek-linked-block is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\">USB 400J<\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"230\" height=\"173\" src=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/enocean-usb-stick.jpg\" alt=\"\" class=\"wp-image-10164\" srcset=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/enocean-usb-stick.jpg 230w, https:\/\/www.enocean.com\/wp-content\/uploads\/Landingpages\/Aruba\/enocean-usb-stick-150x113.jpg 150w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-getwid-accordion has-icon-left\" data-active-element=\"none\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div><\/section>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-9855_46cfd3-17 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-9855_46cfd3-17 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-9855_46cfd3-17\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/section>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8938,"featured_media":9142,"parent":4536,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"class_list":["post-9855","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EnOcean Radio Frequency Selection - EnOcean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.enocean.com\/en\/applications\/partnerships\/enocean-products-select-radio-frequency\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EnOcean Radio Frequency Selection - EnOcean\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.enocean.com\/en\/applications\/partnerships\/enocean-products-select-radio-frequency\/\" \/>\n<meta property=\"og:site_name\" content=\"EnOcean\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-11T09:09:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_IoT__02_2048x613.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"613\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/applications\\\/partnerships\\\/enocean-products-select-radio-frequency\\\/\",\"url\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/applications\\\/partnerships\\\/enocean-products-select-radio-frequency\\\/\",\"name\":\"EnOcean Radio Frequency Selection - EnOcean\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/applications\\\/partnerships\\\/enocean-products-select-radio-frequency\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/applications\\\/partnerships\\\/enocean-products-select-radio-frequency\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.enocean.com\\\/wp-content\\\/uploads\\\/Header\\\/eo_IoT__02_2048x613.jpg\",\"datePublished\":\"2021-09-23T12:30:03+00:00\",\"dateModified\":\"2025-03-11T09:09:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/applications\\\/partnerships\\\/enocean-products-select-radio-frequency\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.enocean.com\\\/en\\\/applications\\\/partnerships\\\/enocean-products-select-radio-frequency\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/applications\\\/partnerships\\\/enocean-products-select-radio-frequency\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.enocean.com\\\/wp-content\\\/uploads\\\/Header\\\/eo_IoT__02_2048x613.jpg\",\"contentUrl\":\"https:\\\/\\\/www.enocean.com\\\/wp-content\\\/uploads\\\/Header\\\/eo_IoT__02_2048x613.jpg\",\"width\":2048,\"height\":613},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/applications\\\/partnerships\\\/enocean-products-select-radio-frequency\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Applications\",\"item\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/applications\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Partnerships\",\"item\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/applications\\\/partnerships\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"EnOcean Radio Frequency Selection\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/\",\"name\":\"EnOcean\",\"description\":\"EnOcean Relaunch\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/#organization\",\"name\":\"EnOcean\",\"url\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.enocean.com\\\/wp-content\\\/uploads\\\/Logos\\\/1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.enocean.com\\\/wp-content\\\/uploads\\\/Logos\\\/1-1.png\",\"width\":500,\"height\":500,\"caption\":\"EnOcean\"},\"image\":{\"@id\":\"https:\\\/\\\/www.enocean.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/enocean\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EnOcean Radio Frequency Selection - EnOcean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.enocean.com\/en\/applications\/partnerships\/enocean-products-select-radio-frequency\/","og_locale":"en_US","og_type":"article","og_title":"EnOcean Radio Frequency Selection - EnOcean","og_url":"https:\/\/www.enocean.com\/en\/applications\/partnerships\/enocean-products-select-radio-frequency\/","og_site_name":"EnOcean","article_modified_time":"2025-03-11T09:09:06+00:00","og_image":[{"width":2048,"height":613,"url":"https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_IoT__02_2048x613.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.enocean.com\/en\/applications\/partnerships\/enocean-products-select-radio-frequency\/","url":"https:\/\/www.enocean.com\/en\/applications\/partnerships\/enocean-products-select-radio-frequency\/","name":"EnOcean Radio Frequency Selection - EnOcean","isPartOf":{"@id":"https:\/\/www.enocean.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.enocean.com\/en\/applications\/partnerships\/enocean-products-select-radio-frequency\/#primaryimage"},"image":{"@id":"https:\/\/www.enocean.com\/en\/applications\/partnerships\/enocean-products-select-radio-frequency\/#primaryimage"},"thumbnailUrl":"https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_IoT__02_2048x613.jpg","datePublished":"2021-09-23T12:30:03+00:00","dateModified":"2025-03-11T09:09:06+00:00","breadcrumb":{"@id":"https:\/\/www.enocean.com\/en\/applications\/partnerships\/enocean-products-select-radio-frequency\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.enocean.com\/en\/applications\/partnerships\/enocean-products-select-radio-frequency\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.enocean.com\/en\/applications\/partnerships\/enocean-products-select-radio-frequency\/#primaryimage","url":"https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_IoT__02_2048x613.jpg","contentUrl":"https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_IoT__02_2048x613.jpg","width":2048,"height":613},{"@type":"BreadcrumbList","@id":"https:\/\/www.enocean.com\/en\/applications\/partnerships\/enocean-products-select-radio-frequency\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.enocean.com\/en\/"},{"@type":"ListItem","position":2,"name":"Applications","item":"https:\/\/www.enocean.com\/en\/applications\/"},{"@type":"ListItem","position":3,"name":"Partnerships","item":"https:\/\/www.enocean.com\/en\/applications\/partnerships\/"},{"@type":"ListItem","position":4,"name":"EnOcean Radio Frequency Selection"}]},{"@type":"WebSite","@id":"https:\/\/www.enocean.com\/en\/#website","url":"https:\/\/www.enocean.com\/en\/","name":"EnOcean","description":"EnOcean Relaunch","publisher":{"@id":"https:\/\/www.enocean.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.enocean.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.enocean.com\/en\/#organization","name":"EnOcean","url":"https:\/\/www.enocean.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.enocean.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.enocean.com\/wp-content\/uploads\/Logos\/1-1.png","contentUrl":"https:\/\/www.enocean.com\/wp-content\/uploads\/Logos\/1-1.png","width":500,"height":500,"caption":"EnOcean"},"image":{"@id":"https:\/\/www.enocean.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/enocean\/"]}]}},"taxonomy_info":[],"featured_image_src_large":["https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_IoT__02_2048x613-1024x307.jpg",1024,307,true],"author_info":{"display_name":"Matteo Bono","author_link":"https:\/\/www.enocean.com\/en\/author\/enocean_bono\/"},"comment_info":0,"uagb_featured_image_src":{"full":["https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_IoT__02_2048x613.jpg",2048,613,false],"thumbnail":["https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_IoT__02_2048x613-150x45.jpg",150,45,true],"medium":["https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_IoT__02_2048x613-300x90.jpg",300,90,true],"medium_large":["https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_IoT__02_2048x613-768x230.jpg",768,230,true],"large":["https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_IoT__02_2048x613-1024x307.jpg",1024,307,true],"1536x1536":["https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_IoT__02_2048x613-1536x460.jpg",1536,460,true],"2048x2048":["https:\/\/www.enocean.com\/wp-content\/uploads\/Header\/eo_IoT__02_2048x613.jpg",2048,613,false]},"uagb_author_info":{"display_name":"Matteo Bono","author_link":"https:\/\/www.enocean.com\/en\/author\/enocean_bono\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/www.enocean.com\/en\/wp-json\/wp\/v2\/pages\/9855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.enocean.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.enocean.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.enocean.com\/en\/wp-json\/wp\/v2\/users\/8938"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enocean.com\/en\/wp-json\/wp\/v2\/comments?post=9855"}],"version-history":[{"count":5,"href":"https:\/\/www.enocean.com\/en\/wp-json\/wp\/v2\/pages\/9855\/revisions"}],"predecessor-version":[{"id":28065,"href":"https:\/\/www.enocean.com\/en\/wp-json\/wp\/v2\/pages\/9855\/revisions\/28065"}],"up":[{"embeddable":true,"href":"https:\/\/www.enocean.com\/en\/wp-json\/wp\/v2\/pages\/4536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enocean.com\/en\/wp-json\/wp\/v2\/media\/9142"}],"wp:attachment":[{"href":"https:\/\/www.enocean.com\/en\/wp-json\/wp\/v2\/media?parent=9855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}